{"id":1522,"date":"2021-07-26T10:24:17","date_gmt":"2021-07-26T13:24:17","guid":{"rendered":"https:\/\/blog.ufes.br\/demografia\/?p=1522"},"modified":"2021-07-26T10:24:17","modified_gmt":"2021-07-26T13:24:17","slug":"a-reducao-da-populacao-jovem","status":"publish","type":"post","link":"https:\/\/blog.ufes.br\/demografia\/2021\/07\/26\/a-reducao-da-populacao-jovem\/","title":{"rendered":"A redu\u00e7\u00e3o da popula\u00e7\u00e3o jovem"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/opiniao.estadao.com.br\/noticias\/notas-e-informacoes,a-reducao-da-populacao-jovem,70003789525\">Chegou-se \u00e0 fase chamada de pa\u00eds maduro. A\u00a0popula\u00e7\u00e3o\u00a0mais idosa tende a crescer mais rapidamente. Cresce tamb\u00e9m, obviamente, a idade m\u00e9dia da popula\u00e7\u00e3o<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chegou-se \u00e0 fase chamada de pa\u00eds maduro. A\u00a0popula\u00e7\u00e3o\u00a0mais idosa tende a crescer mais rapidamente. Cresce tamb\u00e9m, obviamente, a idade m\u00e9dia da popula\u00e7\u00e3o<\/p>\n","protected":false},"author":419,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_uag_custom_page_level_css":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1522","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"post-thumbnail":false},"uagb_author_info":{"display_name":"jhonatan.ribeiro","author_link":"https:\/\/blog.ufes.br\/demografia\/author\/jhonatan_telles-ribeiro\/"},"uagb_comment_info":0,"uagb_excerpt":"Chegou-se \u00e0 fase chamada de pa\u00eds maduro. A\u00a0popula\u00e7\u00e3o\u00a0mais idosa tende a crescer mais rapidamente. Cresce tamb\u00e9m, obviamente, a idade m\u00e9dia da popula\u00e7\u00e3o","_links":{"self":[{"href":"https:\/\/blog.ufes.br\/demografia\/wp-json\/wp\/v2\/posts\/1522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.ufes.br\/demografia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.ufes.br\/demografia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.ufes.br\/demografia\/wp-json\/wp\/v2\/users\/419"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.ufes.br\/demografia\/wp-json\/wp\/v2\/comments?post=1522"}],"version-history":[{"count":1,"href":"https:\/\/blog.ufes.br\/demografia\/wp-json\/wp\/v2\/posts\/1522\/revisions"}],"predecessor-version":[{"id":1523,"href":"https:\/\/blog.ufes.br\/demografia\/wp-json\/wp\/v2\/posts\/1522\/revisions\/1523"}],"wp:attachment":[{"href":"https:\/\/blog.ufes.br\/demografia\/wp-json\/wp\/v2\/media?parent=1522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.ufes.br\/demografia\/wp-json\/wp\/v2\/categories?post=1522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.ufes.br\/demografia\/wp-json\/wp\/v2\/tags?post=1522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}