{"id":1044,"date":"2012-10-19T11:16:02","date_gmt":"2012-10-19T14:16:02","guid":{"rendered":"http:\/\/blog.ufes.br\/patri_lab\/?p=1044"},"modified":"2013-02-04T21:10:18","modified_gmt":"2013-02-04T23:10:18","slug":"apresentacao-de-monografia","status":"publish","type":"post","link":"https:\/\/blog.ufes.br\/patri_lab\/2012\/10\/19\/apresentacao-de-monografia\/","title":{"rendered":"Apresenta\u00e7\u00e3o de Monografia"},"content":{"rendered":"<p>O pesquisador associado <strong>Bruno Amaral de Andrade<\/strong>, apresenta Projeto de Gradua\u00e7\u00e3o (monografia) intitulado &#8220;<em>Uma rota patrimonial para o rio Santa Maria da Vit\u00f3ria [ES]. Instrumento de conserva\u00e7\u00e3o, valoriza\u00e7\u00e3o, requalifica\u00e7\u00e3o e\/ou transforma\u00e7\u00e3o do Patrim\u00f4nio Territorial<\/em>&#8220;, neste ter\u00e7a-feira, 23\/10, \u00e0s 10:30 hrs, no Cemuni III, UFES.<\/p>\n<p>Para acesso \u00e0 apresenta\u00e7\u00e3o do trabalho <a title=\"Rota'\" href=\"http:\/\/www.slideshare.net\/patri_lab\/uma-rota-patrimonial-para-o-baixo-rio-santa-maria-da-vitria-instrumento-de-conservao-valorizao-requalificao-eou-transformao-do-patrimnio-territorial\" target=\"_blank\">clique aqui<\/a>, para ler o trabalho na \u00edntegra consulte a Biblioteca Setorial do Centro de Artes, UFES, a partir de Mar\u00e7o\/2013.<\/p>\n<p><a href=\"http:\/\/blog.ufes.br\/patri_lab\/files\/2012\/10\/divulg.-pg.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-1045\" src=\"http:\/\/blog.ufes.br\/patri_lab\/files\/2012\/10\/divulg.-pg.jpg\" alt=\"\" width=\"808\" height=\"613\" srcset=\"https:\/\/blog.ufes.br\/patri_lab\/files\/2012\/10\/divulg.-pg.jpg 808w, https:\/\/blog.ufes.br\/patri_lab\/files\/2012\/10\/divulg.-pg-300x227.jpg 300w\" sizes=\"auto, (max-width: 808px) 100vw, 808px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Conhe\u00e7a o trabalho de monografia do nosso pesquisador, desenvolvido em paralelo ao subprojeto de pesquisa de Inicia\u00e7\u00e3o Cient\u00edfica 2011\/2012 &#8220;Rio Santa Maria da Vit\u00f3ria, patrim\u00f4nio protagonista do desenvolvimento regional de Santa Leopoldina [ES]&#8221;.<\/p>\n<p>Nos vemos l\u00e1!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O pesquisador associado Bruno Amaral de Andrade, apresenta Projeto de Gradua\u00e7\u00e3o (monografia) intitulado &#8220;Uma rota patrimonial para o rio Santa Maria da Vit\u00f3ria [ES]. Instrumento de conserva\u00e7\u00e3o, valoriza\u00e7\u00e3o, requalifica\u00e7\u00e3o e\/ou transforma\u00e7\u00e3o do Patrim\u00f4nio Territorial&#8220;, neste ter\u00e7a-feira, 23\/10, \u00e0s 10:30 hrs, &hellip; <a href=\"https:\/\/blog.ufes.br\/patri_lab\/2012\/10\/19\/apresentacao-de-monografia\/\">Continue lendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":37,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_uag_custom_page_level_css":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1044","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"post-thumbnail":false},"uagb_author_info":{"display_name":"Bruno de Andrade","author_link":"https:\/\/blog.ufes.br\/patri_lab\/author\/bruno-andrade\/"},"uagb_comment_info":1,"uagb_excerpt":"O pesquisador associado Bruno Amaral de Andrade, apresenta Projeto de Gradua\u00e7\u00e3o (monografia) intitulado &#8220;Uma rota patrimonial para o rio Santa Maria da Vit\u00f3ria [ES]. Instrumento de conserva\u00e7\u00e3o, valoriza\u00e7\u00e3o, requalifica\u00e7\u00e3o e\/ou transforma\u00e7\u00e3o do Patrim\u00f4nio Territorial&#8220;, neste ter\u00e7a-feira, 23\/10, \u00e0s 10:30 hrs, &hellip; Continue lendo &rarr;","_links":{"self":[{"href":"https:\/\/blog.ufes.br\/patri_lab\/wp-json\/wp\/v2\/posts\/1044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.ufes.br\/patri_lab\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.ufes.br\/patri_lab\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.ufes.br\/patri_lab\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.ufes.br\/patri_lab\/wp-json\/wp\/v2\/comments?post=1044"}],"version-history":[{"count":4,"href":"https:\/\/blog.ufes.br\/patri_lab\/wp-json\/wp\/v2\/posts\/1044\/revisions"}],"predecessor-version":[{"id":1206,"href":"https:\/\/blog.ufes.br\/patri_lab\/wp-json\/wp\/v2\/posts\/1044\/revisions\/1206"}],"wp:attachment":[{"href":"https:\/\/blog.ufes.br\/patri_lab\/wp-json\/wp\/v2\/media?parent=1044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.ufes.br\/patri_lab\/wp-json\/wp\/v2\/categories?post=1044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.ufes.br\/patri_lab\/wp-json\/wp\/v2\/tags?post=1044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}