{"id":2544,"date":"2017-11-07T13:04:34","date_gmt":"2017-11-07T15:04:34","guid":{"rendered":"http:\/\/blog.ufes.br\/patri_lab\/?p=2544"},"modified":"2017-11-07T13:57:03","modified_gmt":"2017-11-07T15:57:03","slug":"vi-seminario-patri_lab-2017","status":"publish","type":"post","link":"https:\/\/blog.ufes.br\/patri_lab\/2017\/11\/07\/vi-seminario-patri_lab-2017\/","title":{"rendered":"VI Semin\u00e1rio Patri_Lab &#8211; 2017"},"content":{"rendered":"<p>O Laborat\u00f3rio Patrim\u00f4nio &amp; Desenvolvimento destaca a realiza\u00e7\u00e3o de mais um semin\u00e1rio anual interno de pesquisadores de gradua\u00e7\u00e3o e p\u00f3s-gradua\u00e7\u00e3o, contando com a participa\u00e7\u00e3o do doutorando em Planejamento Urbano pela Universidade Federal de Minas Gerais, UFMG, Bruno Amaral de Andrade.<\/p>\n<div id=\"attachment_2550\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/blog.ufes.br\/patri_lab\/files\/2017\/11\/VI_SEMIN\u00c1RIO_PATRI_LAB.png\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2550\" class=\"wp-image-2550 size-large\" src=\"http:\/\/blog.ufes.br\/patri_lab\/files\/2017\/11\/VI_SEMIN\u00c1RIO_PATRI_LAB-1024x431.png\" alt=\"\" width=\"640\" height=\"269\" srcset=\"https:\/\/blog.ufes.br\/patri_lab\/files\/2017\/11\/VI_SEMIN\u00c1RIO_PATRI_LAB-1024x431.png 1024w, https:\/\/blog.ufes.br\/patri_lab\/files\/2017\/11\/VI_SEMIN\u00c1RIO_PATRI_LAB-300x126.png 300w, https:\/\/blog.ufes.br\/patri_lab\/files\/2017\/11\/VI_SEMIN\u00c1RIO_PATRI_LAB-768x323.png 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><p id=\"caption-attachment-2550\" class=\"wp-caption-text\">Participantes do VI Semin\u00e1rio Patri_Lab &#8211; 2017<\/p><\/div>\n<div id=\"attachment_2548\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/blog.ufes.br\/patri_lab\/files\/2017\/11\/VI-Semin\u00e1rio-Patri_Lab-_-Programa\u00e7\u00e3o.png\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2548\" class=\"wp-image-2548 size-large\" src=\"http:\/\/blog.ufes.br\/patri_lab\/files\/2017\/11\/VI-Semin\u00e1rio-Patri_Lab-_-Programa\u00e7\u00e3o-720x1024.png\" alt=\"\" width=\"640\" height=\"910\" srcset=\"https:\/\/blog.ufes.br\/patri_lab\/files\/2017\/11\/VI-Semin\u00e1rio-Patri_Lab-_-Programa\u00e7\u00e3o-720x1024.png 720w, https:\/\/blog.ufes.br\/patri_lab\/files\/2017\/11\/VI-Semin\u00e1rio-Patri_Lab-_-Programa\u00e7\u00e3o-211x300.png 211w, https:\/\/blog.ufes.br\/patri_lab\/files\/2017\/11\/VI-Semin\u00e1rio-Patri_Lab-_-Programa\u00e7\u00e3o-768x1092.png 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><p id=\"caption-attachment-2548\" class=\"wp-caption-text\">Programa\u00e7\u00e3o VI Semin\u00e1rio Patri_Lab<\/p><\/div>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/blog.ufes.br\/patri_lab\/files\/2017\/11\/VI_SEMIN\u00c1RIO_PATRI_LAB.jpg\"><br \/>\n<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Laborat\u00f3rio Patrim\u00f4nio &amp; Desenvolvimento destaca a realiza\u00e7\u00e3o de mais um semin\u00e1rio anual interno de pesquisadores de gradua\u00e7\u00e3o e p\u00f3s-gradua\u00e7\u00e3o, contando com a participa\u00e7\u00e3o do doutorando em Planejamento Urbano pela Universidade Federal de Minas Gerais, UFMG, Bruno Amaral de Andrade. &hellip; <a href=\"https:\/\/blog.ufes.br\/patri_lab\/2017\/11\/07\/vi-seminario-patri_lab-2017\/\">Continue lendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":319,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_uag_custom_page_level_css":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-2544","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"post-thumbnail":false},"uagb_author_info":{"display_name":"mariana.p.amorim","author_link":"https:\/\/blog.ufes.br\/patri_lab\/author\/mariana-p-amorim\/"},"uagb_comment_info":0,"uagb_excerpt":"O Laborat\u00f3rio Patrim\u00f4nio &amp; Desenvolvimento destaca a realiza\u00e7\u00e3o de mais um semin\u00e1rio anual interno de pesquisadores de gradua\u00e7\u00e3o e p\u00f3s-gradua\u00e7\u00e3o, contando com a participa\u00e7\u00e3o do doutorando em Planejamento Urbano pela Universidade Federal de Minas Gerais, UFMG, Bruno Amaral de Andrade. &hellip; Continue lendo &rarr;","_links":{"self":[{"href":"https:\/\/blog.ufes.br\/patri_lab\/wp-json\/wp\/v2\/posts\/2544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.ufes.br\/patri_lab\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.ufes.br\/patri_lab\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.ufes.br\/patri_lab\/wp-json\/wp\/v2\/users\/319"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.ufes.br\/patri_lab\/wp-json\/wp\/v2\/comments?post=2544"}],"version-history":[{"count":5,"href":"https:\/\/blog.ufes.br\/patri_lab\/wp-json\/wp\/v2\/posts\/2544\/revisions"}],"predecessor-version":[{"id":2555,"href":"https:\/\/blog.ufes.br\/patri_lab\/wp-json\/wp\/v2\/posts\/2544\/revisions\/2555"}],"wp:attachment":[{"href":"https:\/\/blog.ufes.br\/patri_lab\/wp-json\/wp\/v2\/media?parent=2544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.ufes.br\/patri_lab\/wp-json\/wp\/v2\/categories?post=2544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.ufes.br\/patri_lab\/wp-json\/wp\/v2\/tags?post=2544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}