{"id":523,"date":"2019-09-09T12:50:32","date_gmt":"2019-09-09T15:50:32","guid":{"rendered":"http:\/\/blog.ufes.br\/revistauniversidade\/?p=523"},"modified":"2022-11-01T09:57:39","modified_gmt":"2022-11-01T12:57:39","slug":"mais-oportunidades-e-diversidade-na-graduacao","status":"publish","type":"post","link":"https:\/\/blog.ufes.br\/revistauniversidade\/2019\/09\/09\/mais-oportunidades-e-diversidade-na-graduacao\/","title":{"rendered":"Mais oportunidades e diversidade na gradua\u00e7\u00e3o"},"content":{"rendered":"\n<p>\u2013 <em>Por Camila Fregona \u2013<\/em><\/p>\n\n\n\n<p><em><strong>Nos \u00faltimos cinco anos, o n\u00famero de cursos de gradua\u00e7\u00e3o da Ufes cresceu. A oferta de vagas para os estudantes foi ampliada e inclui op\u00e7\u00f5es exclusivas de forma\u00e7\u00e3o no estado e no pa\u00eds<\/strong><\/em><\/p>\n\n\n\n<p>Criada h\u00e1 65 anos com o desafio de formar profissionais, a Universidade Federal do Esp\u00edrito Santo segue evoluindo nessa tarefa, junto a outras relativas a desenvolver e compartilhar conhecimentos. Nos \u00faltimos cinco anos, de 2014 a 2019, o ensino de gradua\u00e7\u00e3o foi marcado pela altera\u00e7\u00e3o na forma de ingresso \u00e0 Universidade: do tradicional vestibular em duas etapas, houve a migra\u00e7\u00e3o, conclu\u00edda em 2017, para o Sistema de Sele\u00e7\u00e3o Unificada (Sisu) do Minist\u00e9rio da Educa\u00e7\u00e3o (MEC), que avalia os estudantes exclusivamente pela nota obtida no Exame Nacional do Ensino M\u00e9dio (Enem). Tamb\u00e9m foram ampliados a oferta de cursos e o n\u00famero vagas e, paralelamente, foram reduzidas as vagas ociosas, o que reafirma o crescimento e o compromisso da Ufes com o ensino superior p\u00fablico. <\/p>\n\n\n\n<p>Nos \u00faltimos cinco anos, houve um aumento de 10% no n\u00famero de vagas, que totalizaram 5.531 em 2019. A amplia\u00e7\u00e3o foi resultado do incremento na quantidade de cursos de gradua\u00e7\u00e3o presencial, que subiu de 92 em 2014 para 104 neste ano. Entre as novidades est\u00e1 a Licenciatura em Educa\u00e7\u00e3o do Campo, criada em 2014 com o objetivo de formar professores para atuar em escolas do ensino b\u00e1sico localizadas em \u00e1reas rurais. A gradua\u00e7\u00e3o pode ser cursada nos campi de Goiabeiras e S\u00e3o Mateus e tem 160 vagas anuais. <\/p>\n\n\n\n<p>Como o curso de dirige a um p\u00fablico que possui v\u00ednculo com o campo, a sele\u00e7\u00e3o \u00e9 feita por edital espec\u00edfico. \u201cEsses cursos formam professores que compreendam a cultura do lugar, que entendam que a forma\u00e7\u00e3o e a atua\u00e7\u00e3o n\u00e3o s\u00e3o descontextualizadas. S\u00e3o cursos que tamb\u00e9m revelam o compromisso da institui\u00e7\u00e3o com o desenvolvimento social\u201d, explica a pr\u00f3-reitora de Gradua\u00e7\u00e3o, Zen\u00f3lia Figueiredo. Outro exemplo \u00e9 a Licenciatura Intercultural Ind\u00edgena, destinada a professores Tupinikim e Guarani que lecionam em aldeias no territ\u00f3rio capixaba. O curso, criado em 2015 com 70 vagas, acontece na Base Oceanogr\u00e1fica da Ufes, no munic\u00edpio de Aracruz, e sua primeira turma de estudantes se forma em 2019.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1245\" height=\"736\" src=\"https:\/\/blog.ufes.br\/revistauniversidade\/files\/2019\/08\/image-5.png\" alt=\"\" class=\"wp-image-694\" \/><figcaption>Segundo a pr\u00f3-reitora de Gradua\u00e7\u00e3o, professora Zen\u00f3lia Figueiredo, a oferta<br> de vagas pelo Sisu possibilitou aumentar a taxa de preenchimento dos cursos. Foto: Jorge Medina\/Ufes<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Nesse per\u00edodo, muitas gradua\u00e7\u00f5es existentes ampliaram as habilita\u00e7\u00f5es ofertadas e o n\u00famero de turmas e de estudantes. Em 2016, a Engenharia de Produ\u00e7\u00e3o, no campus de Goiabeiras, passou a ser oferecido no per\u00edodo noturno, uma amplia\u00e7\u00e3o de 40 vagas, al\u00e9m de dobrar as oportunidades no per\u00edodo vespertino, que passaram de 20 para 40. No Direito, tamb\u00e9m houve o aumento de 10 vagas anuais a partir de 2017, chegando a 120.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Democratiza\u00e7\u00e3o do acesso<\/strong><\/h3>\n\n\n\n<p>Al\u00e9m de ampliar as vagas, a Ufes adotou, desde 2007, um sistema de inclus\u00e3o social em seus processos seletivos. Inicialmente, esse m\u00e9todo reservava 40% das oportunidades dispon\u00edveis para os estudantes que cursaram pelo menos quatro anos das s\u00e9ries do ensino fundamental e todo o ensino m\u00e9dio em escola p\u00fablica, que tivessem renda familiar at\u00e9 sete sal\u00e1rios m\u00ednimos e que n\u00e3o possu\u00edssem nenhum curso de gradua\u00e7\u00e3o completo. Portanto, a primeira resolu\u00e7\u00e3o aprovada na Ufes no sentido de democratizar o acesso ao ensino superior ocorreu bem antes da regulamenta\u00e7\u00e3o federal, que veio em 2012, com a lei n\u00ba 12.711. Por meio dela, 50% das vagas da universidade passaram a ser reservadas para estudantes que cursaram integralmente o ensino m\u00e9dio em escolas p\u00fablicas, com renda familiar inferior a 1,5 sal\u00e1rio m\u00ednimo por pessoa, autodeclarados pretos, pardos e ind\u00edgenas ou pessoas com defici\u00eancia. A partir de ent\u00e3o, esse modelo foi o adotado por todas as institui\u00e7\u00f5es federais de ensino superior do pa\u00eds.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1030\" height=\"638\" src=\"https:\/\/blog.ufes.br\/revistauniversidade\/files\/2019\/08\/image-6.png\" alt=\"\" class=\"wp-image-695\" \/><figcaption>A Ufes j\u00e1 adotava iniciativas de inclus\u00e3o social antes da pol\u00edtica de cotas regulamentada em 2012. Foto: Reprodu\u00e7\u00e3o\/TV Ufes<\/figcaption><\/figure>\n<\/div>\n\n\n<p>A experi\u00eancia antecipada da Ufes com o sistema de reserva de vagas possibilitou que a institui\u00e7\u00e3o desenvolvesse, desde 2008, um plano de assist\u00eancia aos estudantes de gradua\u00e7\u00e3o presencial, a fim de favorecer a sua perman\u00eancia e a conclus\u00e3o do curso superior. Em 2010, o Plano Nacional de Assist\u00eancia Estudantil (Pnaes) estabeleceu um recorte de renda familiar para estudantes assistidos, de at\u00e9 1,5 sal\u00e1rio m\u00ednimo por pessoa. Atualmente, 6 mil estudantes est\u00e3o cadastrados no Programa de Assist\u00eancia Estudantil da Pr\u00f3-Reitoria de Assist\u00eancia Estudantil e Cidadania (Proaeci) e recebem aux\u00edlios para transporte, moradia, material de consumo e alimenta\u00e7\u00e3o (acesso gratuito ao restaurante universit\u00e1rio), al\u00e9m de empr\u00e9stimo estendido de livros.<\/p>\n\n\n\n<p>Outra medida de democratiza\u00e7\u00e3o do acesso ao ensino superior p\u00fablico foi a ado\u00e7\u00e3o do Sisu, a partir de 2014. Naquele ano, o Sisu serviu como forma de ingresso aos cursos com in\u00edcio no segundo semestre nos campi de Alegre e S\u00e3o Mateus. A experi\u00eancia positiva observada legitimou a decis\u00e3o de tornar o Sisu a \u00fanica forma de ingresso nos cursos de gradua\u00e7\u00e3o presencial da institui\u00e7\u00e3o a partir de 2017, eliminando assim o modelo anterior, composto por uma primeira etapa classificat\u00f3ria com base nas notas do Enem e uma segunda etapa discursiva, com provas de reda\u00e7\u00e3o e conhecimentos espec\u00edficos. Algumas gradua\u00e7\u00f5es, contudo, permaneceram com editais de ingresso em separado, devido a especifidades no processo seletivo. Entre eles, est\u00e3o os cursos de M\u00fasica e Letras-Libras, bem como a Licenciatura em Educa\u00e7\u00e3o do Campo. Em 2019, a universidade passou a participar de duas edi\u00e7\u00f5es anuais do Sisu, separando, assim, as entradas para o primeiro e o segundo semestre.<\/p>\n\n\n\n<p>A oferta de vagas por meio do Sisu promoveu uma grande mudan\u00e7a no acesso \u00e0 universidade: com o sistema nacional, estudantes de qualquer unidade federativa do pa\u00eds poderiam participar do processo seletivo sem ter de se deslocar para realizar as provas. A facilidade, contudo, n\u00e3o afetou o perfil de origem dos ingressantes: segundo a Pr\u00f3 -Reitoria de Gradua\u00e7\u00e3o da Ufes (Prograd), o percentual de estudantes vindos de outros estados brasileiros se manteve na casa dos 25%.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/blog.ufes.br\/revistauniversidade\/files\/2019\/08\/Fotos-educa\u00e7\u00e3o-8.jpg\" alt=\"\" class=\"wp-image-701\" \/><figcaption> Mesmo adotando o sistema nacional de ingresso \u00e0 universidade, o percentual de estudantes de fora do Esp\u00edrito Santo na Ufes se manteve na casa dos 25%. Foto: Reprodu\u00e7\u00e3o\/TV Ufes. <\/figcaption><\/figure>\n<\/div>\n\n\n<p>O maior diferencial, no entanto, foi o aumento da taxa de preenchimento dos cursos e a consequente redu\u00e7\u00e3o do n\u00famero de vagas remanescentes. Em 2015, por exemplo, das 4.178 oportunidades ofertadas no VestUfes, 978 n\u00e3o foram preenchidas e passaram por outros processos seletivos de remanejamento, tal como o de vagas surgidas. Em uma an\u00e1lise comparativa, o n\u00famero representava uma ocupa\u00e7\u00e3o em torno de 70%, enquanto em 2018 a taxa saltou para 99%. Isso porque, no Sisu, o candidato j\u00e1 conhece a nota de corte dos cursos na hora de fazer sua escolha e, al\u00e9m disso, pode selecionar uma segunda op\u00e7\u00e3o de gradua\u00e7\u00e3o, caso n\u00e3o seja classificado na primeira. Apesar da facilidade para inscri\u00e7\u00e3o e visualiza\u00e7\u00e3o das chances em determinada \u00e1rea, a Prograd garante que as notas de corte dos cursos foram mantidas no mesmo patamar do vestibular.<\/p>\n\n\n\n<p>Em termos qualitativos, as gradua\u00e7\u00f5es da Ufes t\u00eam apresentado melhoria constante nos \u00faltimos cinco anos, segundo o \u00cdndice Geral de Cursos do MEC. Desde 2012, a quase totalidade dos cursos da Ufes foi avaliada com conceitos positivos, o que representa nota igual ou maior que 3 no Conceito Preliminar de Curso (CPC). O indicador considera a nota dos estudantes no Exame Nacional de Desempenho dos Estudantes (Enade); o Indicador de Diferen\u00e7a entre os Desempenhos Esperado e Observado (IDD), que mede o quanto o curso de gradua\u00e7\u00e3o agregou ao desenvolvimento do discente; o perfil dos professores, incluindo o regime de trabalho e atitula\u00e7\u00e3o; e o question\u00e1rio aplicado aos estudantes sobre as percep\u00e7\u00f5es do processo formativo. Dos 86 cursos avaliados no \u00faltimo ciclo do Enade, 50 obtiveram conceito 4 no CPC e 35 deles, igual a 3.<\/p>\n\n\n\n<p>O MEC tamb\u00e9m realiza avalia\u00e7\u00f5es<em> in loco<\/em>, tanto para cursos que n\u00e3o participaram do Enade naquele per\u00edodo quanto para aqueles que obtiveram CPC menor do que 3. Desde 2014, foram visitados 42 cursos da Ufes e todos obtiveram Conceito de Curso positivo (maior ou igual a 3). Quatro deles alcan\u00e7aram a nota m\u00e1xima (5): Estat\u00edstica, em 2019; Filosofia, na modalidade a dist\u00e2ncia, em 2018; Pedagogia, no campus de S\u00e3o Mateus, em 2017; e Arquivologia, em 2016.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1030\" height=\"638\" src=\"https:\/\/blog.ufes.br\/revistauniversidade\/files\/2019\/08\/image-9.png\" alt=\"\" class=\"wp-image-702\" \/><figcaption> Dos 86 cursos avaliados no \u00faltimo ciclo do Enade, 50 obtiveram conceito 4 no CPC e 35 deles foram avaliados com nota 3. Foto: Reprodu\u00e7\u00e3o\/TV Ufes. <\/figcaption><\/figure>\n<\/div>\n\n\n<p>De acordo com a Secretaria de Avalia\u00e7\u00e3o Institucional (Seavin), os n\u00fameros se refletem em boas classifica\u00e7\u00f5es para a Ufes, como por exemplo a 26\u00aa posi\u00e7\u00e3o no Ranking Universit\u00e1rio Folha, entre as 196 institui\u00e7\u00f5es de ensino superior (IES) brasileiras avaliadas. A Seavin tem buscado, junto com a Secretaria de Rela\u00e7\u00f5es Internacionais, inserir a Ufes nos rankings internacionais, levantando os dados necess\u00e1rios para as an\u00e1lises.<\/p>\n\n\n\n<p><strong>Leia tamb\u00e9m:<br><\/strong><a href=\"https:\/\/blog.ufes.br\/revistauniversidade\/2019\/08\/13\/ensino-a-distancia-amplia-interiorizacao\/\">Ensino a dist\u00e2ncia amplia a interioriza\u00e7\u00e3o<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong> Refer\u00eancia<\/strong><\/h3>\n\n\n\n<p>\u00danica universidade p\u00fablica no Esp\u00edrito Santo, a Ufes \u00e9 refer\u00eancia em ensino superior no estado. A capilaridade proporcionada por meio de seus 27 polos de ensino a dist\u00e2ncia e a interioriza\u00e7\u00e3o de suas atividades, com a atua\u00e7\u00e3o dos campi universit\u00e1rios nos munic\u00edpios de Alegre, no sul do estado, e S\u00e3o Mateus, no norte, s\u00e3o alguns exemplos da import\u00e2ncia do trabalho desenvolvido pela institui\u00e7\u00e3o, que oferece uma ampla gama de cursos.<\/p>\n\n\n\n<p>No Esp\u00edrito Santo, algumas gradua\u00e7\u00f5es, na modalidade presencial, s\u00e3o encontradas exclusivamente na Ufes. Alguns exemplos s\u00e3o Arquivologia, Artes Pl\u00e1sticas, Biblioteconomia, Cinema e Audiovisual, Engenharia de Alimentos, Geologia, Oceanografia, Terapia Ocupacional e Zootecnia.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>\u2013 Por Camila Fregona \u2013 Nos \u00faltimos cinco anos, o n\u00famero de cursos de gradua\u00e7\u00e3o da Ufes cresceu. A oferta de vagas para os estudantes <a class=\"mh-excerpt-more\" href=\"https:\/\/blog.ufes.br\/revistauniversidade\/2019\/09\/09\/mais-oportunidades-e-diversidade-na-graduacao\/\" title=\"Mais oportunidades e diversidade na gradua\u00e7\u00e3o\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":350,"featured_media":698,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_uag_custom_page_level_css":"","footnotes":""},"categories":[7,46,9],"tags":[],"class_list":["post-523","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chamadinhas","category-edicao-010","category-noticias"],"uagb_featured_image_src":{"full":["https:\/\/blog.ufes.br\/revistauniversidade\/files\/2019\/08\/Fotos-educa\u00e7\u00e3o-1.jpg",1920,1080,false],"thumbnail":["https:\/\/blog.ufes.br\/revistauniversidade\/files\/2019\/08\/Fotos-educa\u00e7\u00e3o-1.jpg",150,84,false],"medium":["https:\/\/blog.ufes.br\/revistauniversidade\/files\/2019\/08\/Fotos-educa\u00e7\u00e3o-1.jpg",300,169,false],"medium_large":["https:\/\/blog.ufes.br\/revistauniversidade\/files\/2019\/08\/Fotos-educa\u00e7\u00e3o-1.jpg",768,432,false],"large":["https:\/\/blog.ufes.br\/revistauniversidade\/files\/2019\/08\/Fotos-educa\u00e7\u00e3o-1.jpg",1024,576,false],"1536x1536":["https:\/\/blog.ufes.br\/revistauniversidade\/files\/2019\/08\/Fotos-educa\u00e7\u00e3o-1.jpg",1536,864,false],"2048x2048":["https:\/\/blog.ufes.br\/revistauniversidade\/files\/2019\/08\/Fotos-educa\u00e7\u00e3o-1.jpg",1920,1080,false],"mh-magazine-lite-slider":["https:\/\/blog.ufes.br\/revistauniversidade\/files\/2019\/08\/Fotos-educa\u00e7\u00e3o-1.jpg",779,438,false],"mh-magazine-lite-content":["https:\/\/blog.ufes.br\/revistauniversidade\/files\/2019\/08\/Fotos-educa\u00e7\u00e3o-1.jpg",678,381,false],"mh-magazine-lite-large":["https:\/\/blog.ufes.br\/revistauniversidade\/files\/2019\/08\/Fotos-educa\u00e7\u00e3o-1.jpg",678,381,false],"mh-magazine-lite-medium":["https:\/\/blog.ufes.br\/revistauniversidade\/files\/2019\/08\/Fotos-educa\u00e7\u00e3o-1.jpg",326,183,false],"mh-magazine-lite-small":["https:\/\/blog.ufes.br\/revistauniversidade\/files\/2019\/08\/Fotos-educa\u00e7\u00e3o-1.jpg",80,45,false]},"uagb_author_info":{"display_name":"lidia.hora","author_link":"https:\/\/blog.ufes.br\/revistauniversidade\/author\/lidia_gurgel-neves-hora\/"},"uagb_comment_info":0,"uagb_excerpt":"\u2013 Por Camila Fregona \u2013 Nos \u00faltimos cinco anos, o n\u00famero de cursos de gradua\u00e7\u00e3o da Ufes cresceu. A oferta de vagas para os estudantes [...]","_links":{"self":[{"href":"https:\/\/blog.ufes.br\/revistauniversidade\/wp-json\/wp\/v2\/posts\/523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.ufes.br\/revistauniversidade\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.ufes.br\/revistauniversidade\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.ufes.br\/revistauniversidade\/wp-json\/wp\/v2\/users\/350"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.ufes.br\/revistauniversidade\/wp-json\/wp\/v2\/comments?post=523"}],"version-history":[{"count":18,"href":"https:\/\/blog.ufes.br\/revistauniversidade\/wp-json\/wp\/v2\/posts\/523\/revisions"}],"predecessor-version":[{"id":2466,"href":"https:\/\/blog.ufes.br\/revistauniversidade\/wp-json\/wp\/v2\/posts\/523\/revisions\/2466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.ufes.br\/revistauniversidade\/wp-json\/wp\/v2\/media\/698"}],"wp:attachment":[{"href":"https:\/\/blog.ufes.br\/revistauniversidade\/wp-json\/wp\/v2\/media?parent=523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.ufes.br\/revistauniversidade\/wp-json\/wp\/v2\/categories?post=523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.ufes.br\/revistauniversidade\/wp-json\/wp\/v2\/tags?post=523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}